{"id":327,"date":"2010-09-23T03:54:22","date_gmt":"2010-09-23T02:54:22","guid":{"rendered":"http:\/\/bodhicharya.org\/manyroads\/?p=327"},"modified":"2011-02-10T23:14:38","modified_gmt":"2011-02-10T22:14:38","slug":"pourquoi-le-bouddhisme","status":"publish","type":"post","link":"https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/","title":{"rendered":"POURQUOI le BOUDDHISME ?"},"content":{"rendered":"<p><strong>\u00ab\u00a0La vie de chacun d\u2019entre nous est marqu\u00e9e par une triple anxi\u00e9t\u00e9\u00a0: la peur de la destruction, le d\u00e9sespoir devant l\u2019absurde et la d\u00e9tresse de l\u2019isolement\u00a0\u00bb Karlfried Graf D\u00fcrckhem<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Quand on a toute sa vie durant, baign\u00e9 dans la culture occidentale et c\u00f4toy\u00e9 les diff\u00e9rents aspects de la philosophie et de la spiritualit\u00e9 occidentale, il peut \u00eatre \u00e9clairant de retrouver le cheminement qui finalement a conduit vers le Bouddhisme pour d\u00e9couvrir les sources qui\u00a0 y ont contribu\u00e9,\u00a0 pour peser la sinc\u00e9rit\u00e9 de cet engagement et aussi s\u2019assurer de son adh\u00e9sion \u00e0 ces enseignements\u00a0; c\u2019est pourquoi au lendemain de ma d\u00e9cision si tardive, j\u2019aimerai faire un retour en arri\u00e8re pour d\u00e9couvrir le fil rouge qui m\u2019a amen\u00e9 \u00e0 faire ce pas.<\/strong><\/p>\n<p><strong>Il m\u2019importe aussi de r\u00e9fl\u00e9chir comment harmoniser mon attachement et<\/strong><strong>mon appartenance aux valeurs occidentales en\u00a0 y int\u00e9grant cette rencontre avec l\u2019Orient.<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Trois \u00e9l\u00e9ments ont, je crois, \u00e9t\u00e9 d\u00e9terminants dans ma jeunesse\u00a0 et peuvent apporter un \u00e9clairage \u00e0 ce que je suis (\u00a0il faut ajouter que je suis n\u00e9e en 1927)\u00a0:<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>1\u00b0 Dans mon enfance, d\u00e8s l\u2019\u00e2ge de 6 ans, des circonstances familiales difficiles ont conduit mes parents \u00e0 me mettre dans un pensionnat, avec une autre s\u0153ur plus \u00e2g\u00e9e et cela pendant 5 ans.<\/strong><\/p>\n<p><strong>J\u2019 y ai d\u00e9couvert\u00a0 le sentiment de\u00a0 solitude, avec ses peurs nocturnes . Cependant je voulais r\u00e9pondre \u00e0 la demande de ma m\u00e8re \u00ab\u00a0d\u2019\u00eatre raisonnable\u00a0\u00bb\u00a0 j\u2018ai alors d\u00e9velopp\u00e9 un int\u00e9r\u00eat (compensatoire sans doute) pour le savoir, la connaissance que j\u2019ai toujours privil\u00e9gi\u00e9 depuis.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>2\u00b0 Dans mon adolescence, de retour au foyer familial\u00a0: la guerre\u00a0!<\/strong><\/p>\n<p><strong>Un basculement \u00e9vident des valeurs d\u2019une civilisation \u00e0 laquelle on croyait,\u00a0<\/strong><strong>\u00a0vers un monde violent o\u00f9 s\u2019affrontent des pays si proches pourtant. Je suis, depuis, devenue une inconditionnelle de la non-violence et antimilitariste convaincue.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>3\u00b0 La religion catholique, celle de ma famille, de mes \u00e9coles et des mouvements de jeunesse au sein desquels j\u2019ai milit\u00e9 . <\/strong><\/p>\n<p><strong>\u00a0J\u2019ai dirig\u00e9 d\u00e8s mes 20 ans une maison de vacances pour\u00a0 <\/strong><strong>jeunes filles\u00a0. Ce qui tr\u00e8s t\u00f4t (trop\u00a0t\u00f4t ?) m\u2019a amen\u00e9 \u00e0 assumer des responsabilit\u00e9s. <\/strong><\/p>\n<p><strong>J\u2019ai cependant eu assez vite l\u2019impression de ne pas avoir re\u00e7u lors de cette \u00e9ducation\u00a0 les donn\u00e9es pour un bon \u00e9quilibre de vie, ou pour mieux dire un plein \u00e9panouissement .<\/strong><\/p>\n<p><strong>Trop de questions restaient pour moi sans r\u00e9ponses\u00a0: place de la sexualit\u00e9, de la femme, des dogmes impos\u00e9s, pourquoi cette culpabilisation mise en avant et cons\u00e9quemment cette difficult\u00e9 \u00e0 s\u2019accepter, la pr\u00e9sence du mal et de la souffrance, bref le sens de la vie , le pourquoi de cet existence \u2026<\/strong><\/p>\n<p><strong>(A ce propos, je retrouve une analyse sur cette \u00e9poque de mon \u00e9ducation religieuse catholique dans \u00ab\u00a0L\u2019Evangile d\u2019un libre penseur\u00a0\u00bb de Gabriel Ringlet , pr\u00eatre th\u00e9ologien \u00ab\u00a0Quand je vois dans quel infantilisme, parfois, on a pu maintenir les chr\u00e9tiens, dans quelle niaiserie, dans quel refoulement, quelle culpabilit\u00e9\u2026 pardonnez-moi mais une terrible col\u00e8re m\u2019envahit. Je ne peux supporter qu\u2019on transforme un Evangile vivant en bouillon pour les morts ,\u00a0 p.150.\u00a0\u00bb) <\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Apr\u00e8s ces trois donn\u00e9es qui n\u2019ont pour but que de me situer au moment o\u00f9 j\u2019aborde ma vie d\u2019adulte et d\u2019y rechercher le fil rouge qui par un long chemin m\u2019a men\u00e9 au Bouddhisme.<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Je crois bien me rappeler que ma premi\u00e8re d\u00e9couverte du Tibet, je la dois \u00e0 Alexandra David Neel . Ses r\u00e9cits donnaient toutefois pour moi une image d\u2019un monde int\u00e9ressant certes mais ferm\u00e9 et \u00e9sot\u00e9rique.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>En dehors de ma vie professionnelle ( j\u2019\u00e9tais assistante sociale dans une usine d\u2019une r\u00e9gion industrielle) c\u2019est surtout par la lecture que peu \u00e0 peu j\u2019ai eu connaissance de la spiritualit\u00e9 orientale et parfois nomm\u00e9ment du Bouddhisme . C\u2019est sans doute Aldous Huxley dont j\u2019ai d\u00e9couvert les essais apr\u00e8s la guerre qui m\u2019a\u00a0 le premier donn\u00e9 une vision\u00a0 positive du Bouddhisme\u00a0: dans \u00ab\u00a0Le plus sot animal\u00a0\u00bb (en anglais Proper Studies) \u00ab\u00a0La Fin et les Moyens\u00a0\u00bb (Ends and Means). J\u2019avoue garder\u00a0 maintenant encore une place favorite dans mes lectures \u00e0 cet auteur qui m\u2019a ouvert des perspectives vers une spiritualit\u00e9 plus ouverte et plus \u00e9quilibr\u00e9e.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Moins s\u00e9rieusement, je n\u2019oublie pas qu\u2019en Belgique, nous avons b\u00e9n\u00e9fici\u00e9 d\u00e8s 1960 de la parution de \u00ab\u00a0\u00a0\u00a0Tintin au Tibet \u00a0\u00bb par Herg\u00e9.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>D\u2019autre part, je suis et reste attach\u00e9e profond\u00e9ment \u00e0 des auteurs occidentaux qui posent un questionnement sur le sens de la vie, et dont l\u2019inqui\u00e9tude va parfois jusqu\u2019\u00e0 avancer la th\u00e9orie de son absurdit\u00e9\u00a0: Albert Camus et son humanisme chaleureux , Cioran et sa d\u00e9tresse.<\/strong><\/p>\n<p><strong>Mes premiers contacts moins livresques je les dois \u00e0 Arnaud Desjardins dont j\u00a0\u2019ai suivi une s\u00e9rie de conf\u00e9rences \u00e0 la radio au d\u00e9but des ann\u00e9es 1960. J\u2019ai achet\u00e9 alors \u00ab\u00a0A la recherche du Soi\u00a0\u00bb \u00ab\u00a0Monde moderne et Sagesse Ancienne\u00a0\u00bb et un livre sur Gurdjieff. Je me suis aussi abonn\u00e9e d\u00e8s l\u2019annonce de sa parution \u00e0 une revue\u00a0\u00ab\u00a0Plan\u00e8te\u00a0\u00bb en octobre 61 dirig\u00e9e par Louis Pauwels qui se voulait aller \u00e0 la recherche de civilisations culturelles anciennes et d\u2019 aujourd\u2019hui mais parfois lointaines, qui apportaient d\u2019autres r\u00e9ponses que l\u2019Occident. Gr\u00e2ce \u00e0 elle, j\u2019ai d\u00e9couvert des \u00e9crits de Teilhard de Chardin , Julian Huxley et m\u00eame de certains voyageurs qui revenaient de monast\u00e8res tib\u00e9tains. Cette revue me confortait aussi dans le malaise que j\u2019\u00e9prouvais vis-\u00e0-vis du colonialisme et\u00a0 de l\u2019endoctrinement des populations indig\u00e8nes particuli\u00e8rement au Congo belge car elle adoptait enfin une ouverture positive aux diff\u00e9rentes r\u00e9ponses que l\u2019humanit\u00e9 avait et donnait encore au sens de l\u2019existence et \u00e0 l\u2019 aide pour vivre que chacun pouvait y trouver.\u00a0\u00a0<\/strong><\/p>\n<p><strong>En dehors des livres, les Arts et sp\u00e9cialement la musique ont \u00e9t\u00e9 et sont toujours pour moi des havres de paix , de s\u00e9r\u00e9nit\u00e9 qui \u00e9veille la part la meilleure en nous-m\u00eame.La musique de chambre sp\u00e9cialement m\u2019a accompagn\u00e9 toute ma vie, m\u2019a aid\u00e9\u00a0 \u00e0 vivre et je citerai Cioran\u00a0\u00ab\u00a0Nous ne sentons vraiment que nous avons \u00ab\u00a0une \u00e2me\u00a0\u00bb\u00a0 que lorsque nous \u00e9coutons de la musique\u00a0\u00bb(Cahiers p.102) Bien que\u00a0 n\u2019\u00e9tant\u00a0 qu\u2019une simple m\u00e9lomane , je ne puis ne pas mentionner ce qui a \u00e9t\u00e9 et est encore pour moi l\u2019apport essentiel et sp\u00e9cifique de l\u2019Occident dans la spiritualit\u00e9, l\u2019Art faisant entrevoir une\u00a0 dimension qui nous transcende.<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>J\u2019avais, comme chacun, suivi avec d\u00e9solation le drame que vivait le Tibet sans vraiment le d\u00e9couvrir dans toute sa port\u00e9e . Il est certain toutefois que la fuite du Dala\u00ef- Lama et son arriv\u00e9e en Inde a permis d\u2019 en mieux comprendre toute la trag\u00e9die.Lors de l\u2019attribution de son prix Nobel de la Paix en 1989, l\u2019Europe et le monde d\u00e9couvraient la bont\u00e9, la sagesse et le rayonnement de celui qui \u00e9tait le meilleur repr\u00e9sentant du Bouddhisme Tib\u00e9tain, mais bien avant cela, les reportages et les images relataient, sans doute en partie, le \u00ab\u00a0g\u00e9nocide culturel\u00a0\u00bb que vivait la population rest\u00e9e au pays.\u00a0<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>En 1983 un tournant dans ma vie\u00a0: je rejoins le parti \u00e9cologiste naissant. <\/strong><strong>J\u2019avais d\u00e9couvert au \u00ab\u00a0Pays Noir\u00a0\u00bb la pollution, ses incidences sur la sant\u00e9,la d\u00e9t\u00e9rioration de notre plan\u00e8te, la condition ouvri\u00e8re ,les discriminations hommes \u2013femmes mais aussi le besoin d\u2019\u00e9thique dans le monde politique, le manque de participation du citoyen \u00e0 la gestion du pays. Ce parti avait comme ambition de \u00ab\u00a0faire de la politique autrement\u00a0\u00bb. Ses d\u00e9buts ont \u00e9t\u00e9 difficiles et m\u2019ont amen\u00e9 \u00e0 m\u2019impliquer davantage et \u00e0 accepter des responsabilit\u00e9s plus prenantes que je n\u2019avais imagin\u00e9 et cela jusqu\u2019en 1994.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>C\u2019est donc bien tardivement que j\u2019ai souhait\u00e9 approfondir les r\u00e9ponses que le\u00a0 Bouddhisme apportait tant sur le plan philosophique que dans ses pr\u00e9ceptes\u00a0 de vie. J\u2019avais eu l\u2019occasion au plan politique de suivre de pr\u00e8s le dossier du Tibet et le comportement de la population. Je d\u00e9couvrais aussi ses affinit\u00e9s avec l\u2019Ecologie qui mettait l\u2019homme au sein de la nature sans pr\u00e9rogative mais soulignait au contraire ses responsabilit\u00e9s\u00a0\u2026<\/strong><\/p>\n<p><strong>Mais j\u2019ignorais alors o\u00f9 trouver les enseignements que je souhaitais\u00a0. Je suivais r\u00e9guli\u00e8rement les \u00e9missions Bouddhistes sur France 2 qui un jour \u00e0 conseill\u00e9 l\u2019achat d\u2019un Guide de Ph.Cornu o\u00f9 j\u2019ai trouv\u00e9 l\u2019adresse et les coordonn\u00e9es de l\u2019Institut Yeunten Ling \u00e0 Huy. C\u2019est l\u00e0 que j\u2019ai commenc\u00e9 \u00e0 approcher les enseignements\u00a0 tr\u00e8s r\u00e9guli\u00e8rement pendant les week-ends d\u00e9s 2000.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>J\u2019avais d\u00e9j\u00e0 beaucoup lu sur le Bouddhisme mais d\u00e9couvrir les enseignements vivants est une exp\u00e9rience irrempla\u00e7able et de plus, dans <\/strong><strong>une atmosph\u00e8re paisible et conviviale. Ce qui m\u2019a frapp\u00e9 et que j\u2019ai appr\u00e9ci\u00e9, c\u2019est qu\u2019apr\u00e8s l\u2019enseignement, il y avait place pour les questions. Et puis j\u2019ai enfin d\u00e9couvert la m\u00e9ditation, le calme du Temple\u00a0; le recueillement des participants favorisant l\u2019approche de cette pratique que je ne trouvais pas facile . La pri\u00e8re dans la religion qui m\u2019\u00e9tait famili\u00e8re et habituelle est bien diff\u00e9rente car c\u2019est une orientation des pens\u00e9es vers un Etre et est plus une impulsion \u2026 La m\u00e9ditation que je m\u2019efforce de pratiquer depuis n\u00e9cessite pour moi un environnement et un calme autour de moi. Curieusement la pr\u00e9sence d\u2019autres m\u00e9ditants est une aide , il n\u2019emp\u00eache que je dois avouer que je suis encore une pi\u00e8tre m\u00e9ditante m\u00eame si de temps \u00e0 autre j\u2019ai ressenti une paix et un bien-\u00eatre inattendu, et entrevu ce que peut apporter la m\u00e9ditation\u2026. Mais je n\u2019ai fait que l\u2019entrevoir\u2026.<\/strong><\/p>\n<p><strong>\u00a0J<\/strong><strong>\u2019ai relu mes notes de cette \u00e9poque et retrouv\u00e9 le plaisir de la d\u00e9couverte d\u2019une philosophie bien structur\u00e9e \u00e0 laquelle s\u2019ajoutait une finesse d\u2019analyse psychologique qui m\u2019apparaissait tout \u00e0 fait convaincante et contemporaine.<\/strong><\/p>\n<p><strong>Cependant je me rappelle \u00eatre rest\u00e9e perplexe devant les rituels, le c\u00e9r\u00e9monial, toute l\u2019atmosph\u00e8re color\u00e9e tib\u00e9taine (les enseignements \u00e9taient donn\u00e9s en tib\u00e9tain). Il est vrai que les lamas \u00e9taient tib\u00e9tains et qu\u2019ils souhaitaient sans doute maintenir et propager cette culture en danger au pays, mais je doutais d\u00e9j\u00e0 de pouvoir assimiler cet exotisme et ces pratiques \u00e9sot\u00e9riques.Par contre, j\u2019adh\u00e9rais facilement aux vertus transcendantes (ou Paramitas) persuad\u00e9e que c\u2019\u00e9tait l\u00e0 le chemin pour la r\u00e9alisation de l\u2019\u00eatre humain m\u00eame si elles m\u2019apparaissaient comme une voie difficile d\u2019acc\u00e8s\u00a0: la Sagesse notamment si \u00e9loign\u00e9e de la vie occidentale\u2026mais aussi la patience\u00a0!<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>En mai 2001, sur\u00a0 le conseil d\u2019une amie bouddhiste rencontr\u00e9e \u00e0 Huy, j\u2019ai \u00e9t\u00e9 \u00e0 une journ\u00e9e d\u2019un enseignement de Ringu Tulku Rimpoch\u00e9. C\u2019\u00e9tait au programme\u00a0: un simple questions-r\u00e9ponses , l\u2019enseignement \u00e9tait donn\u00e9 en anglais et traduit.J\u2019ai aid\u00e9 une voisine dans la peine \u00e0 poser une question par \u00e9crit, elle \u00e9tait en\u00a0 grande d\u00e9tresse, seule avec un enfant handicap\u00e9 et ne trouvait pas d\u2019issue \u00e0 ses probl\u00e8mes.<\/strong><\/p>\n<p><strong>L\u2019attitude recueillie, le calme et la s\u00e9r\u00e9nit\u00e9 donn\u00e9e dans la r\u00e9ponse par Rimpoch\u00e9 m\u2019ont fait d\u00e9couvrir vers quelle profondeur pouvait conduire cette spiritualit\u00e9. Comme assistante sociale, je savais la difficult\u00e9 \u00e0 trouver la juste attitude. Le lendemain, cette dame et moi avons \u00e9t\u00e9 \u00e0 son enseignement du soir et depuis, je sais qu\u2019elle a trouv\u00e9 une issue favorable tant pour elle que pour son fils.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Si je relate cette exp\u00e9rience personnelle, c\u2019est que je crois vraiment que la rencontre avec le Bouddhisme passe obligatoirement par ces trois \u00e9tapes\u00a0: la lecture, l\u2019enseignement et la rencontre d\u2019un Ma\u00eetre qui incarne ce qui vous\u00a0 a \u00e9t\u00e9 donn\u00e9 intellectuellement. Je sais qu\u2019apr\u00e8s, il faut la pratique et son int\u00e9gration dans le quotidien, surmonter les obstacles qui interviennent sur le chemin de l\u2019adoption et de l\u2019adh\u00e9sion \u00e0 cette nouvelle spiritualit\u00e9.\u00a0 <\/strong><strong>(J\u2019h\u00e9site \u00e0 utiliser le mot religion tellement galvaud\u00e9 et trahi trop souvent par ses d\u00e9rives.) Ce fut un long chemin pour moi et difficile .Pourtant bien des \u00e9l\u00e9ments du Bouddhisme me s\u00e9duisaient d\u2019autant que certains\u00a0\u00e9taient <\/strong><strong>ancr\u00e9s en moi: la non-violence, la tol\u00e9rance,la compassion et l\u2019amour pour tous ,le respect de la nature .D\u2019autres \u00e9l\u00e9ments m\u2019ont paru assez vite convaincants et apportant m\u00eame une r\u00e9ponse \u00e0 des questions toujours rest\u00e9es sans r\u00e9ponse jusqu\u2019alors\u00a0:l\u2019interd\u00e9pendance, l\u2019impermanence (\u00e9vidente\u00a0!) la r\u00e9incarnation (m\u00eame si ce que j\u2019en con\u00e7ois n\u2019est peut-\u00eatre pas orthodoxe).<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Depuis, j\u2019ai suivi le plus r\u00e9guli\u00e8rement possible les enseignements par Ringu Tulku Rimpoch\u00e9 . Ceux-ci me sont apparus plus clairs, plus accessibles aussi .Sa grande souplesse ainsi que sa compr\u00e9hension permettaient aussi de saisir que l\u2019essentiel \u00e9tait de trouver et\u00a0 prendre dans le message bouddhique ce qui \u00e9tait bon pour soi que c\u2019\u00e9tait l\u00e0 l\u2019important..<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Tr\u00e8s s\u00e9duite au d\u00e9part, j\u2019ai ressenti ensuite une r\u00e9sistance pour m\u2019engager que je n\u2019explique pas ais\u00e9ment.La pratique de la m\u00e9ditation m\u2019a paru soudain moins accessible.<\/strong><\/p>\n<p><strong>D\u2019autre part, ma sant\u00e9 se d\u00e9gradait. La vieillesse entra\u00eenait pour moi des difficult\u00e9s suppl\u00e9mentaires. L\u2019ou\u00efe,bien n\u00e9cessaire \u00e0 la fois dans la relation avec l\u2019entourage et aussi les enseignements. Les douleurs rhumatismales qui sont un handicap \u00e0 rester serein et tranquille.Et puis les d\u00e9placements vers les Centres devenus difficiles alors que, j\u2019ai besoin de sentir une communion avec d\u2019autres pour pratiquer.C\u2019est peut-\u00eatre l\u00e0 que r\u00e9side mon probl\u00e8me .Je sais qu\u2019il serait sage d\u2019accepter les limites impos\u00e9es par la vieillesse mais entre le savoir et le vivre il y a une distance incommensurable que chacun de nous est appel\u00e9 \u00e0 conna\u00eetre dans d\u2019autres domaines.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>De fait, le Bouddhisme peut para\u00eetre comme une spiritualit\u00e9 de solitaire si on ne participe pas \u00e0 la vie d\u2019un Centre, la m\u00e9ditation, m\u00eame si elle d\u00e9di\u00e9e \u00e0 tous les \u00eatres, est un repli vers soi tr\u00e8s diff\u00e9rent des cultes monoth\u00e9istes o\u00f9 on se met sous le regard d\u2019un Etre.<\/strong><\/p>\n<p><strong>Bien s\u00fbr, la \u00ab\u00a0Sangha\u00a0\u00bb\u00a0: mais pour moi, je l\u2019avoue j\u2019y vois une notion encore assez th\u00e9orique et lointaine..<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>En 2002, j\u2019avais assist\u00e9 \u00e0 une conf\u00e9rence donn\u00e9e par\u00a0 Ma\u00eetre Roland Yuno Rech qui m\u2019avait beaucoup \u00e9clair\u00e9 pour comprendre la diff\u00e9rence d\u2019approche entre les spiritualit\u00e9s orientales et occidentales . Moine Zen, mais occidental, il mettait le doigt sur l\u2019\u00e9quilibre qu\u2019apportait le Bouddhisme \u00e0\u00a0 l\u2019Europ\u00e9en d\u00e9sorient\u00e9\u00a0: pour lui, le Bouddhisme\u00a0 permettait de retrouver l\u2019Unit\u00e9 en donnant plus de sens \u00e0 la vie\u00a0et abandonner ainsi des dualit\u00e9s pr\u00e9judiciables \u00e0 l\u2019\u00e9panouissement\u00a0: dualit\u00e9 entre le corps et l\u2019esprit, entre soi et les autres, entre l\u2019homme et la nature , entre le mat\u00e9riel et\u00a0 spirituel, entre les moyens et la fin, entre la vie et la mort..<\/strong><\/p>\n<p><strong>Je r\u00e9sume \u00e9videmment \u00e0 ma mani\u00e8re et comme je peux un enseignement qui m\u2019a\u00a0 paru une r\u00e9ponse forte pour expliquer l\u2019attrait de l\u2019Occident pour le Bouddhisme et l\u2019 apport essentiel de celui-ci dans notre monde d\u00e9sax\u00e9.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Alors pourquoi tant d\u2019h\u00e9sitations de ma part \u00e0 faire un pas d\u00e9finitif\u00a0? Je n\u2019ai pas, il est vrai, une nature \u00e0 m\u2019engager \u00e0 la l\u00e9g\u00e8re et je sentais encore des r\u00e9ticences vis-\u00e0-vis de certaines pratiques, peut-\u00eatre aussi par une certaine paresse\u2026mais r\u00e9ellement, il y avait un recul en moi comme si je devais abandonner quelque chose . M\u00eame si je reste attach\u00e9e au message de l\u2019Evangile, ses Institutions ne me semblent pas porteur de ce message\u00a0 et j\u2019avais rompu avec elles\u00a0: trop de richesses, trop de pouvoirs , trop de certitudes absolues\u00a0 et de diktats sans nuances. Pourtant tant de catholiques\u00a0 ont port\u00e9 et portaient encore d\u2019une fa\u00e7on remarquable et exemplaire le message du Christ. Quelles complexit\u00e9s engendr\u00e9es par le comportement humain\u00a0!.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Il a fallu une hospitalisation inopin\u00e9e et en urgence en octobre 2009 pour m\u2019apporter le coup de pouce n\u00e9cessaire pour prendre enfin une d\u00e9cision .\u00a0\u00a0 (J\u2019ai lu derni\u00e8rement dans une \u00e9tude consacr\u00e9e au vieillissement que celui-ci entra\u00eenait une r\u00e9sistance au changement, j\u2019ai trouv\u00e9 l\u00e0 une justification \u00e0 mes tergiversations\u2026 ah, ce besoin de toujours se justifier\u00a0!) Etant en danger, l\u2019infirmi\u00e8re qui r\u00e9digeait mon dossier m\u2019a demand\u00e9 ma religion\u00a0: <\/strong><strong>apr\u00e8s une minute de r\u00e9flexion, j\u2019ai r\u00e9pondu \u00ab\u00a0Bouddhisme\u00a0\u00bb.Pendant les semaines de mon s\u00e9jour \u00e0 l\u2019h\u00f4pital, j\u2019ai r\u00e9fl\u00e9chi \u00e0 ce qui m\u2019avait pouss\u00e9 \u00e0 donner cette r\u00e9ponse\u00a0:pour commencer, sinc\u00e8rement, je ne me voyait pas mourir avec l\u2019\u00e9tiquette \u00ab\u00a0sans religion\u00a0\u00bb j\u2019ai toujours v\u00e9cu persuad\u00e9e que les valeurs spirituelles sont essentielles et portent l\u2019esp\u00e9rance de l\u2019humanit\u00e9 quand elles sont empreintes de l\u2019ouverture vers l\u2019autre. J\u2019 ai mis en exergue \u00e0 mon r\u00e9cit, un texte de K-G D\u00fcrckheim, qui m\u2019a paru r\u00e9sumer admirablement les d\u00e9tresses de la vie humaine\u00a0; Pour moi, c\u2019est le Bouddhisme qui y r\u00e9pond le mieux et\u00a0\u00a0 sa philosophie et ses vertus transcendantes , c\u0153ur de la pratique, correspondent le mieux \u00e0 ma vision d\u2019un \u00eatre accompli .<\/strong><\/p>\n<p><strong>\u00a0Mais surtout, la bont\u00e9 et la compr\u00e9hension encourageante de Ringu Tulku Rimpoch\u00e9 ont \u00e9t\u00e9 pour moi ces derni\u00e8res ann\u00e9es une aide et un r\u00e9confort important. Ma r\u00e9ponse ne pouvait pas \u00eatre autre.<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>En mars 2010, lors de la venue de Rimpoch\u00e9 \u00e0 Bruxelles et gr\u00e2ce aussi \u00e0 l\u2019aide efficace et rapide de Fran\u00e7ois Henrard , malgr\u00e9 un programme tr\u00e8s charg\u00e9 Rimpoch\u00e9 a bien voulu me donner refuge dans le Temple de Kagyu Samye Dzong, merci \u00e0 eux pour cette hospitalit\u00e9 impromptue.J\u2019ai re\u00e7u le beau nom de \u00ab\u00a0The Torch of Dharma\u00a0\u00bb.<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Je ne crois pas \u00eatre une tr\u00e8s bonne bouddhiste. Je ne sais pas si, sur le chemin qui me reste, je pourrais progresser.Je sais pourtant qu\u2019il ne faut\u00a0 pas que mon esprit rationnel trop occidental sans doute me perturbe , mais\u00a0 qu\u2019il me faut trouver la voie pour harmoniser en moi ce que j\u2019ai re\u00e7u de l\u2019Occident avec ses doutes, ses questions, ses valeurs et la voie spirituelle que j\u2019ai choisi avec certaines pratiques et rituels encore difficiles et peu accessibles pour moi .Mais je sais que je suis heureuse d\u2019avoir rejoint cette spiritualit\u00e9 qui allie merveilleusement la compassion et la sagesse et que je souhaite qu\u2019apr\u00e8s ma mort, je puisses , dans une autre existence peut-\u00eatre ,\u00a0 y \u00eatre meilleure. <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 05\/08\/2010\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Denise N\u00e9lis<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0La vie de chacun d\u2019entre nous est marqu\u00e9e par une triple anxi\u00e9t\u00e9\u00a0: la peur de la destruction, le d\u00e9sespoir devant l\u2019absurde et la d\u00e9tresse de l\u2019isolement\u00a0\u00bb Karlfried Graf D\u00fcrckhem \u00a0Quand on a toute sa vie durant, baign\u00e9 dans la culture occidentale et c\u00f4toy\u00e9 les diff\u00e9rents aspects de la philosophie et de la spiritualit\u00e9 occidentale, il [&hellip;]<\/p>\n","protected":false},"author":340,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-327","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>POURQUOI le BOUDDHISME ? - Many Roads<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/pourquoi-le-bouddhisme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/pourquoi-le-bouddhisme\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"POURQUOI le BOUDDHISME ?\",\"datePublished\":\"2010-09-23T02:54:22+00:00\",\"dateModified\":\"2011-02-10T22:14:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/pourquoi-le-bouddhisme\\\/\"},\"wordCount\":3232,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/#organization\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/pourquoi-le-bouddhisme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/pourquoi-le-bouddhisme\\\/\",\"url\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/pourquoi-le-bouddhisme\\\/\",\"name\":\"POURQUOI le BOUDDHISME ? - Many Roads\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/#website\"},\"datePublished\":\"2010-09-23T02:54:22+00:00\",\"dateModified\":\"2011-02-10T22:14:38+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/pourquoi-le-bouddhisme\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/#website\",\"url\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/\",\"name\":\"Many Roads\",\"description\":\"Bodhicharya&#039;s e-magazine\",\"publisher\":{\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/#organization\",\"name\":\"Many Roads\",\"url\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d2wipdjmobk1g8.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/05\\\/22152403\\\/LOGO.png\",\"contentUrl\":\"https:\\\/\\\/d2wipdjmobk1g8.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/05\\\/22152403\\\/LOGO.png\",\"width\":506,\"height\":136,\"caption\":\"Many Roads\"},\"image\":{\"@id\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/bodhicharya.org\\\/manyroads\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POURQUOI le BOUDDHISME ? - Many Roads","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/","twitter_misc":{"Written by":"","Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/#article","isPartOf":{"@id":"https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/"},"author":{"name":"","@id":""},"headline":"POURQUOI le BOUDDHISME ?","datePublished":"2010-09-23T02:54:22+00:00","dateModified":"2011-02-10T22:14:38+00:00","mainEntityOfPage":{"@id":"https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/"},"wordCount":3232,"commentCount":2,"publisher":{"@id":"https:\/\/bodhicharya.org\/manyroads\/#organization"},"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/","url":"https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/","name":"POURQUOI le BOUDDHISME ? - Many Roads","isPartOf":{"@id":"https:\/\/bodhicharya.org\/manyroads\/#website"},"datePublished":"2010-09-23T02:54:22+00:00","dateModified":"2011-02-10T22:14:38+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodhicharya.org\/manyroads\/pourquoi-le-bouddhisme\/"]}]},{"@type":"WebSite","@id":"https:\/\/bodhicharya.org\/manyroads\/#website","url":"https:\/\/bodhicharya.org\/manyroads\/","name":"Many Roads","description":"Bodhicharya&#039;s e-magazine","publisher":{"@id":"https:\/\/bodhicharya.org\/manyroads\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodhicharya.org\/manyroads\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bodhicharya.org\/manyroads\/#organization","name":"Many Roads","url":"https:\/\/bodhicharya.org\/manyroads\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bodhicharya.org\/manyroads\/#\/schema\/logo\/image\/","url":"https:\/\/d2wipdjmobk1g8.cloudfront.net\/wp-content\/uploads\/sites\/4\/2017\/05\/22152403\/LOGO.png","contentUrl":"https:\/\/d2wipdjmobk1g8.cloudfront.net\/wp-content\/uploads\/sites\/4\/2017\/05\/22152403\/LOGO.png","width":506,"height":136,"caption":"Many Roads"},"image":{"@id":"https:\/\/bodhicharya.org\/manyroads\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/bodhicharya.org\/manyroads\/author\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"shareaholic-thumbnail":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false,"mailchimp":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bodhicharya.org\/manyroads\/author\/"},"uagb_comment_info":2,"uagb_excerpt":"\u00ab\u00a0La vie de chacun d\u2019entre nous est marqu\u00e9e par une triple anxi\u00e9t\u00e9\u00a0: la peur de la destruction, le d\u00e9sespoir devant l\u2019absurde et la d\u00e9tresse de l\u2019isolement\u00a0\u00bb Karlfried Graf D\u00fcrckhem \u00a0Quand on a toute sa vie durant, baign\u00e9 dans la culture occidentale et c\u00f4toy\u00e9 les diff\u00e9rents aspects de la philosophie et de la spiritualit\u00e9 occidentale, il&hellip;","_links":{"self":[{"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/posts\/327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/users\/340"}],"replies":[{"embeddable":true,"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/comments?post=327"}],"version-history":[{"count":0,"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/posts\/327\/revisions"}],"wp:attachment":[{"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/media?parent=327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/categories?post=327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bodhicharya.org\/manyroads\/wp-json\/wp\/v2\/tags?post=327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}